{"id":9396,"date":"2010-06-01T22:12:03","date_gmt":"2010-06-02T04:12:03","guid":{"rendered":"http:\/\/www.ricosyfamosos.org\/?p=9396"},"modified":"2010-06-01T22:12:03","modified_gmt":"2010-06-02T04:12:03","slug":"descanso-en-hawaii-para-megan-fox","status":"publish","type":"post","link":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/","title":{"rendered":"Descanso en Hawaii para Megan Fox"},"content":{"rendered":"<div align=\"justify\">Mientras se prepara para comenzar con la promoci\u00f3n de su nueva pel\u00edcula, la actriz m\u00e1s sensual, <strong>Megan Fox<\/strong> se tom\u00f3 un descanso en las playas de Hawaii.<\/div>\n<p><\/p>\n<div align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2010\/06\/Megan-Fox-01-450x635.jpg\" alt=\"Megan Fox-01\" title=\"Megan Fox-01\" width=\"450\" height=\"635\" class=\"aligncenter size-medium wp-image-9397\" srcset=\"http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2010\/06\/Megan-Fox-01-450x635.jpg 450w, http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2010\/06\/Megan-Fox-01.jpg 468w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/div>\n<p><\/p>\n<div align=\"justify\">Junto a su novio, una de las estrellas de Beverly Hills 90210, <strong>Brian Green<\/strong>, <strong>Megan Fox<\/strong> se pase\u00f3 por la playa una y otra vez.<\/div>\n<p>\n<!--more--><\/p>\n<div align=\"justify\">En diferentes bikinis, feliz y mostrando su trabajado torso, la joven no dud\u00f3 en refrescarse y compartir momentos de amor con su pareja.<\/div>\n<p><\/p>\n<div align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2010\/06\/Megan-Fox-02-450x554.jpg\" alt=\"Megan Fox-02\" title=\"Megan Fox-02\" width=\"450\" height=\"554\" class=\"aligncenter size-medium wp-image-9398\" srcset=\"http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2010\/06\/Megan-Fox-02-450x554.jpg 450w, http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2010\/06\/Megan-Fox-02.jpg 468w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2010\/06\/Megan-Fox-03.jpg\" alt=\"SPL168897_002\" title=\"SPL168897_002\" width=\"450\" height=\"675\" class=\"aligncenter size-full wp-image-9399\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2010\/06\/Megan-Fox-04.jpg\" alt=\"SPL168897_009\" title=\"SPL168897_009\" width=\"450\" height=\"675\" class=\"aligncenter size-full wp-image-9400\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2010\/06\/Megan-Fox-05.jpg\" alt=\"SPL168897_013\" title=\"SPL168897_013\" width=\"450\" height=\"675\" class=\"aligncenter size-full wp-image-9401\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2010\/06\/Megan-Fox-06.jpg\" alt=\"SPL168897_016\" title=\"SPL168897_016\" width=\"450\" height=\"675\" class=\"aligncenter size-full wp-image-9402\" \/><\/div>\n<p><\/p>\n<p>Fotos: thesuperficial.com ; dailymail.co.uk<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras se prepara para comenzar con la promoci\u00f3n de su nueva pel\u00edcula, la actriz m\u00e1s sensual, Megan Fox se tom\u00f3 un descanso en las playas de Hawaii. Junto a su novio, una de las estrellas de Beverly Hills 90210, Brian Green, Megan Fox se pase\u00f3 por la playa una y otra vez.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50,45,42,31,44,32],"tags":[1573,310],"class_list":["post-9396","post","type-post","status-publish","format-standard","hentry","category-fotos-de-famosas","category-fotos-de-famosos","category-noticias-de-actores","category-noticias-de-actrices","category-noticias-de-cine","category-noticias-generales","tag-brian-green","tag-megan-fox"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Famosos\"\/>\n\t<link rel=\"canonical\" href=\"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Noticias de famosos | Noticias de famosos, celebridades, famosas, rumores, noticias de musica, noticias del cine, movie trailers, trailers de peliculas, videos de famosos, noticias paparazzi, noticias de cantantes, noticias de cine, noticias de tv, fotos de famosos, noticias de cantantes, Celebrity Ooopss!, escandalos de Hollywood, noticias de television, fotos de famosas y m\u00e1s!\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Descanso en Hawaii para Megan Fox | Ricosyfamosos.org\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-06-02T04:12:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2010-06-02T04:12:03+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Descanso en Hawaii para Megan Fox | Ricosyfamosos.org\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/2010\\\/06\\\/01\\\/descanso-en-hawaii-para-megan-fox\\\/#article\",\"name\":\"Descanso en Hawaii para Megan Fox | Ricosyfamosos.org\",\"headline\":\"Descanso en Hawaii para Megan Fox\",\"author\":{\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/wp-content\\\/uploads\\\/2010\\\/06\\\/Megan-Fox-01.jpg\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/2010\\\/06\\\/01\\\/descanso-en-hawaii-para-megan-fox\\\/#articleImage\",\"width\":468,\"height\":661},\"datePublished\":\"2010-06-01T22:12:03-06:00\",\"dateModified\":\"2010-06-01T22:12:03-06:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/2010\\\/06\\\/01\\\/descanso-en-hawaii-para-megan-fox\\\/#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/2010\\\/06\\\/01\\\/descanso-en-hawaii-para-megan-fox\\\/#webpage\"},\"articleSection\":\"Fotos de famosas, Fotos de famosos, Noticias de actores, Noticias de actrices, Noticias de cine, Noticias generales, Brian Green, megan fox\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/2010\\\/06\\\/01\\\/descanso-en-hawaii-para-megan-fox\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.ricosyfamosos.org\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/category\\\/noticias-de-actrices\\\/#listItem\",\"name\":\"Noticias de actrices\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/category\\\/noticias-de-actrices\\\/#listItem\",\"position\":2,\"name\":\"Noticias de actrices\",\"item\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/category\\\/noticias-de-actrices\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/2010\\\/06\\\/01\\\/descanso-en-hawaii-para-megan-fox\\\/#listItem\",\"name\":\"Descanso en Hawaii para Megan Fox\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/2010\\\/06\\\/01\\\/descanso-en-hawaii-para-megan-fox\\\/#listItem\",\"position\":3,\"name\":\"Descanso en Hawaii para Megan Fox\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/category\\\/noticias-de-actrices\\\/#listItem\",\"name\":\"Noticias de actrices\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/#organization\",\"name\":\"Noticias de famosos\",\"description\":\"Noticias de famosos, celebridades, famosas, rumores, noticias de musica, noticias del cine, movie trailers, trailers de peliculas, videos de famosos, noticias paparazzi, noticias de cantantes, noticias de cine, noticias de tv, fotos de famosos, noticias de cantantes, Celebrity Ooopss!, escandalos de Hollywood, noticias de television, fotos de famosas y m\\u00e1s!\",\"url\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/author\\\/admin\\\/#author\",\"url\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/author\\\/admin\\\/\",\"name\":\"Famosos\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/2010\\\/06\\\/01\\\/descanso-en-hawaii-para-megan-fox\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b87429700c9df7458382f4e6e1517f9472b9308586140716d42c32c543afd9d2?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Famosos\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/2010\\\/06\\\/01\\\/descanso-en-hawaii-para-megan-fox\\\/#webpage\",\"url\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/2010\\\/06\\\/01\\\/descanso-en-hawaii-para-megan-fox\\\/\",\"name\":\"Descanso en Hawaii para Megan Fox | Ricosyfamosos.org\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/2010\\\/06\\\/01\\\/descanso-en-hawaii-para-megan-fox\\\/#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/index.php\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2010-06-01T22:12:03-06:00\",\"dateModified\":\"2010-06-01T22:12:03-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/#website\",\"url\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/\",\"name\":\"Noticias de famosos\",\"description\":\"Noticias de famosos, celebridades, famosas, rumores, noticias de musica, noticias del cine, movie trailers, trailers de peliculas, videos de famosos, noticias paparazzi, noticias de cantantes, noticias de cine, noticias de tv, fotos de famosos, noticias de cantantes, Celebrity Ooopss!, escandalos de Hollywood, noticias de television, fotos de famosas y m\\u00e1s!\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.ricosyfamosos.org\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Descanso en Hawaii para Megan Fox | Ricosyfamosos.org","description":"","canonical_url":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/#article","name":"Descanso en Hawaii para Megan Fox | Ricosyfamosos.org","headline":"Descanso en Hawaii para Megan Fox","author":{"@id":"http:\/\/www.ricosyfamosos.org\/index.php\/author\/admin\/#author"},"publisher":{"@id":"http:\/\/www.ricosyfamosos.org\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2010\/06\/Megan-Fox-01.jpg","@id":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/#articleImage","width":468,"height":661},"datePublished":"2010-06-01T22:12:03-06:00","dateModified":"2010-06-01T22:12:03-06:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/#webpage"},"isPartOf":{"@id":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/#webpage"},"articleSection":"Fotos de famosas, Fotos de famosos, Noticias de actores, Noticias de actrices, Noticias de cine, Noticias generales, Brian Green, megan fox"},{"@type":"BreadcrumbList","@id":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/www.ricosyfamosos.org#listItem","position":1,"name":"Home","item":"http:\/\/www.ricosyfamosos.org","nextItem":{"@type":"ListItem","@id":"http:\/\/www.ricosyfamosos.org\/index.php\/category\/noticias-de-actrices\/#listItem","name":"Noticias de actrices"}},{"@type":"ListItem","@id":"http:\/\/www.ricosyfamosos.org\/index.php\/category\/noticias-de-actrices\/#listItem","position":2,"name":"Noticias de actrices","item":"http:\/\/www.ricosyfamosos.org\/index.php\/category\/noticias-de-actrices\/","nextItem":{"@type":"ListItem","@id":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/#listItem","name":"Descanso en Hawaii para Megan Fox"},"previousItem":{"@type":"ListItem","@id":"http:\/\/www.ricosyfamosos.org#listItem","name":"Home"}},{"@type":"ListItem","@id":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/#listItem","position":3,"name":"Descanso en Hawaii para Megan Fox","previousItem":{"@type":"ListItem","@id":"http:\/\/www.ricosyfamosos.org\/index.php\/category\/noticias-de-actrices\/#listItem","name":"Noticias de actrices"}}]},{"@type":"Organization","@id":"http:\/\/www.ricosyfamosos.org\/#organization","name":"Noticias de famosos","description":"Noticias de famosos, celebridades, famosas, rumores, noticias de musica, noticias del cine, movie trailers, trailers de peliculas, videos de famosos, noticias paparazzi, noticias de cantantes, noticias de cine, noticias de tv, fotos de famosos, noticias de cantantes, Celebrity Ooopss!, escandalos de Hollywood, noticias de television, fotos de famosas y m\u00e1s!","url":"http:\/\/www.ricosyfamosos.org\/"},{"@type":"Person","@id":"http:\/\/www.ricosyfamosos.org\/index.php\/author\/admin\/#author","url":"http:\/\/www.ricosyfamosos.org\/index.php\/author\/admin\/","name":"Famosos","image":{"@type":"ImageObject","@id":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b87429700c9df7458382f4e6e1517f9472b9308586140716d42c32c543afd9d2?s=96&d=mm&r=g","width":96,"height":96,"caption":"Famosos"}},{"@type":"WebPage","@id":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/#webpage","url":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/","name":"Descanso en Hawaii para Megan Fox | Ricosyfamosos.org","inLanguage":"es-ES","isPartOf":{"@id":"http:\/\/www.ricosyfamosos.org\/#website"},"breadcrumb":{"@id":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/#breadcrumblist"},"author":{"@id":"http:\/\/www.ricosyfamosos.org\/index.php\/author\/admin\/#author"},"creator":{"@id":"http:\/\/www.ricosyfamosos.org\/index.php\/author\/admin\/#author"},"datePublished":"2010-06-01T22:12:03-06:00","dateModified":"2010-06-01T22:12:03-06:00"},{"@type":"WebSite","@id":"http:\/\/www.ricosyfamosos.org\/#website","url":"http:\/\/www.ricosyfamosos.org\/","name":"Noticias de famosos","description":"Noticias de famosos, celebridades, famosas, rumores, noticias de musica, noticias del cine, movie trailers, trailers de peliculas, videos de famosos, noticias paparazzi, noticias de cantantes, noticias de cine, noticias de tv, fotos de famosos, noticias de cantantes, Celebrity Ooopss!, escandalos de Hollywood, noticias de television, fotos de famosas y m\u00e1s!","inLanguage":"es-ES","publisher":{"@id":"http:\/\/www.ricosyfamosos.org\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Noticias de famosos | Noticias de famosos, celebridades, famosas, rumores, noticias de musica, noticias del cine, movie trailers, trailers de peliculas, videos de famosos, noticias paparazzi, noticias de cantantes, noticias de cine, noticias de tv, fotos de famosos, noticias de cantantes, Celebrity Ooopss!, escandalos de Hollywood, noticias de television, fotos de famosas y m\u00e1s!","og:type":"article","og:title":"Descanso en Hawaii para Megan Fox | Ricosyfamosos.org","og:url":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/","article:published_time":"2010-06-02T04:12:03+00:00","article:modified_time":"2010-06-02T04:12:03+00:00","twitter:card":"summary","twitter:title":"Descanso en Hawaii para Megan Fox | Ricosyfamosos.org"},"aioseo_meta_data":{"post_id":"9396","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 02:58:26","updated":"2025-06-04 16:31:31","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/www.ricosyfamosos.org\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/www.ricosyfamosos.org\/index.php\/category\/noticias-de-actrices\/\" title=\"Noticias de actrices\">Noticias de actrices<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDescanso en Hawaii para Megan Fox\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"http:\/\/www.ricosyfamosos.org"},{"label":"Noticias de actrices","link":"http:\/\/www.ricosyfamosos.org\/index.php\/category\/noticias-de-actrices\/"},{"label":"Descanso en Hawaii para Megan Fox","link":"http:\/\/www.ricosyfamosos.org\/index.php\/2010\/06\/01\/descanso-en-hawaii-para-megan-fox\/"}],"_links":{"self":[{"href":"http:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/posts\/9396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/comments?post=9396"}],"version-history":[{"count":0,"href":"http:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/posts\/9396\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/media?parent=9396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/categories?post=9396"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/tags?post=9396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}