{"id":2354,"date":"2009-05-26T08:33:53","date_gmt":"2009-05-26T14:33:53","guid":{"rendered":"http:\/\/www.ricosyfamosos.org\/?p=2354"},"modified":"2009-05-26T08:33:53","modified_gmt":"2009-05-26T14:33:53","slug":"tom-hanks-tuvo-que-dejar-su-casa","status":"publish","type":"post","link":"https:\/\/www.ricosyfamosos.org\/index.php\/2009\/05\/26\/tom-hanks-tuvo-que-dejar-su-casa\/","title":{"rendered":"Tom Hanks tuvo que dejar su casa"},"content":{"rendered":"<div align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.ricosyfamosos.org\/wp-content\/uploads\/2009\/05\/tom-hanks-01.jpg\" alt=\"tom-hanks-01\" title=\"tom-hanks-01\" width=\"278\" height=\"425\" class=\"aligncenter size-full wp-image-2355\" \/><\/div>\n<p><\/p>\n<div align=\"justify\">La estrella de Hollywood <strong>Tom Hanks<\/strong> no tiene m\u00e1s opci\u00f3n que mudarse de casa y hasta a tenido que quemar toda su ropa.<br \/>\nNo es por ninguna ceremonia asociada a esas religiones y sectas extra\u00f1as que hay en el medio, sino porque su casa fue atacada por zorrinos. Nada m\u00e1s ni nada menos.<br \/>\nEl actor y su mujer han intentado de todo para quitar el olor, pero es imposible e insoportable.<br \/>\n<strong>Tom Hanks<\/strong> afirm\u00f3 que ya prob\u00f3 de todo y nada ha funcionado:<\/p>\n<blockquote><p>\u201cDicen que la \u00fanica manera de terminar con ese olor terrible es con jugo de tomate pero es mentira&#8230; Hemos lavado la casa con inmensas cantidades de jugo y no ayuda. \u00a1El olor es simplemente insoportable y se mantiene durante d\u00edas!&#8230;\u201d<\/p><\/blockquote>\n<p>Tuvieron que quemar su ropa del olor que ten\u00eda y tampoco ha contribuido a solucionar el problema:<\/p>\n<blockquote><p>\u201cTuve que quemar la ropa y tendremos que irnos de aqu\u00ed porque el olor es demasiado fuerte&#8230; \u00a1Nos tenemos que mudar!&#8230;\u201d<\/p><\/blockquote>\n<p>Pues Tom, parece que no te queda m\u00e1s opci\u00f3n&#8230;tendr\u00e1s que mudarte&#8230;<\/p><\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La estrella de Hollywood Tom Hanks no tiene m\u00e1s opci\u00f3n que mudarse de casa y hasta a tenido que quemar toda su ropa. No es por ninguna ceremonia asociada a esas religiones y sectas extra\u00f1as que hay en el medio, sino porque su casa fue atacada por zorrinos. Nada m\u00e1s ni nada menos. El actor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42,44,32],"tags":[815,864],"class_list":["post-2354","post","type-post","status-publish","format-standard","hentry","category-noticias-de-actores","category-noticias-de-cine","category-noticias-generales","tag-tom-hanks","tag-tom-hanks-casa"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/posts\/2354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/comments?post=2354"}],"version-history":[{"count":0,"href":"https:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/posts\/2354\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/media?parent=2354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/categories?post=2354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ricosyfamosos.org\/index.php\/wp-json\/wp\/v2\/tags?post=2354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}